{"id":59104,"date":"2022-03-13T10:41:11","date_gmt":"2022-03-13T09:41:11","guid":{"rendered":"https:\/\/fpmdcorp.com\/?page_id=59104"},"modified":"2023-06-26T17:14:32","modified_gmt":"2023-06-26T15:14:32","slug":"accoglienza","status":"publish","type":"page","link":"https:\/\/fpmdcorp.com\/it\/","title":{"rendered":"Accoglienza"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row type=&#8221;vc_default&#8221; full_width=&#8221;stretch_row_content_no_spaces&#8221; full_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; css_animation=&#8221;bounceInRight&#8221; full_width_row=&#8221;true&#8221; css=&#8221;.vc_custom_1687792410939{margin-top: -50px !important;background-image: url(https:\/\/fpmdcorp.com\/wp-content\/uploads\/2023\/06\/fpmd-intro-hp.jpg?id=65543) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243; css=&#8221;.vc_custom_1660668917228{padding-top: 50px !important;padding-right: 50px !important;padding-bottom: 50px !important;padding-left: 50px !important;background-color: rgba(2,2,2,0.09) !important;*background-color: rgb(2,2,2) !important;border-radius: 15px !important;}&#8221;][vc_column_text]<\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">FPMD CORP<\/span><\/h1>\n<h3 style=\"text-align: center;\"><span style=\"color: #ffffff;\">PROMOZIONI, ORGANIZZAZIONI ED EVENTI<\/span><\/h3>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Benvenuti nel sito ufficiale di FPMD Corp, siamo una societ\u00e0 Internet internazionale: il nostro team completamente remoto lavora in pi\u00f9 di 15 paesi diversi (Francia, Belgio, Portogallo, Regno Unito, Hong Kong, USA, Italia, Spagna, Germania, Canada, &#8230;.) e offriamo i nostri corsi in tutto il mondo in diverse traduzioni.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row][vc_row margin_top=&#8221;80&#8243; margin_bottom=&#8221;48&#8243; css=&#8221;.vc_custom_1660809882550{margin-bottom: 80px !important;}&#8221; el_class=&#8221;text-centered&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;]<section class=\"shortcode-teaser frame-fancy frame-on fadeInLeft animate-element\"><div class=\"shortcode-teaser-img\"><a class=\"layzr-bg rollover\" href=\"https:\/\/fpmdcorp.com\/it\/attivita\/\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy-load\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 300 100&#039;%2F%3E\" width=\"300\" height=\"100\" alt=\"Activit\u00e9s\" data-srcset=\"https:\/\/fpmdcorp.com\/wp-content\/uploads\/2023\/06\/fpmd-activites-300x100-1.jpg 300w\" data-src=\"https:\/\/fpmdcorp.com\/wp-content\/uploads\/2023\/06\/fpmd-activites-300x100-1.jpg\" \/><\/a><\/div><div class=\"shortcode-teaser-content text-big\"><h3>ACTTIVITA<\/h3>\n<div class=\"gap\" style=\"line-height: 15px; height: 15px;\"><\/div><a href=\"https:\/\/fpmdcorp.com\/it\/attivita\/\/\" class=\"btn-shortcode dt-btn-s dt-btn default-btn-color default-btn-hover-color default-btn-bg-color default-btn-bg-hover-color fadeIn animate-element animation-builder\" id=\"dt-btn-1\"><i class=\"fa fa-chevron-circle-right\"><\/i><span>SCOPRIRE<\/span><\/a><\/p>\n<div class=\"gap\" style=\"line-height: 10px; height: 10px;\"><\/div>\n<\/div><\/section>[vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<section class=\"shortcode-teaser frame-fancy frame-on fadeInLeft animate-element\"><div class=\"shortcode-teaser-img\"><a class=\"layzr-bg rollover\" href=\"https:\/\/fpmdcorp.com\/it\/diario\/\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy-load\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 300 100&#039;%2F%3E\" width=\"300\" height=\"100\" alt=\"Des auteurs, formateurs et conf\u00e9renciers de renom reconnus dans le monde entier\" data-srcset=\"https:\/\/fpmdcorp.com\/wp-content\/uploads\/2023\/06\/fpmd-agenda-300x100-1.jpg 300w\" data-src=\"https:\/\/fpmdcorp.com\/wp-content\/uploads\/2023\/06\/fpmd-agenda-300x100-1.jpg\" \/><\/a><\/div><div class=\"shortcode-teaser-content text-big\"><h3>DIARIO<\/h3>\n<div class=\"gap\" style=\"line-height: 15px; height: 15px;\"><\/div><style type=\"text\/css\">#dt-btn-2 {background: default;}#dt-btn-2:hover {background: default;}<\/style><a href=\"https:\/\/fpmdcorp.com\/it\/diario\/\" class=\"btn-shortcode dt-btn-s dt-btn default-btn-color default-btn-hover-color fadeIn animate-element animation-builder\" id=\"dt-btn-2\"><i class=\"fa fa-chevron-circle-right\"><\/i><span>SCOPRIRE<\/span><\/a><\/p>\n<div class=\"gap\" style=\"line-height: 10px; height: 10px;\"><\/div>\n<\/div><\/section>[vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;]<section class=\"shortcode-teaser frame-fancy frame-on fadeInLeft animate-element\"><div class=\"shortcode-teaser-img\"><a class=\"layzr-bg rollover\" href=\"https:\/\/fpmdcorp.com\/it\/prodotti\/\"><img loading=\"lazy\" decoding=\"async\" class=\"lazy-load\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 300 100&#039;%2F%3E\" width=\"300\" height=\"100\" alt=\"Inscriptions\" data-srcset=\"https:\/\/fpmdcorp.com\/wp-content\/uploads\/2023\/06\/fpmd-inscriptions-300x100-1.jpg 300w\" data-src=\"https:\/\/fpmdcorp.com\/wp-content\/uploads\/2023\/06\/fpmd-inscriptions-300x100-1.jpg\" \/><\/a><\/div><div class=\"shortcode-teaser-content text-big\"><h3>REGISTRAZIONI<\/h3>\n<div class=\"gap\" style=\"line-height: 15px; height: 15px;\"><\/div><style type=\"text\/css\">#dt-btn-3 {background: default;}#dt-btn-3:hover {background: default;}<\/style><a href=\"https:\/\/fpmdcorp.com\/it\/prodotti\/\" class=\"btn-shortcode dt-btn-s dt-btn default-btn-color default-btn-hover-color fadeIn animate-element animation-builder\" id=\"dt-btn-3\"><i class=\"fa fa-chevron-circle-right\"><\/i><span>SCOPRIRE<\/span><\/a><\/p>\n<div class=\"gap\" style=\"line-height: 10px; height: 10px;\"><\/div>\n<\/div><\/section>[vc_empty_space][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;1&#8243; padding_top=&#8221;60&#8243; padding_bottom=&#8221;60&#8243; bg_repeat=&#8221;repeat&#8221; el_class=&#8221;text-centered&#8221;][vc_column][vc_row_inner gap=&#8221;30&#8243;][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text css_animation=&#8221;fadeInRight&#8221;]<\/p>\n<h3>LA STRUTURRA<\/h3>\n<p>La sua missione \u00e8 focalizzata sull&#8217;apertura delle coscienze e sull&#8217;ecologia personale attraverso l&#8217;organizzazione, la produzione, la promozione e la diffusione di eventi (conferenze, workshop, formazione, simposi, fiere) per tutto il pubblico.<\/p>\n<p>David come fondatore di questa struttura vuole essere:<\/p>\n<p>un facilitatore che fornisce una piattaforma organizzativa e logistica per i soccorritori.<\/p>\n<p>un promotore sia per le persone che desiderano accedere a eventi di questo tipo sia per gli stakeholder che aprono il proprio settore geografico.<\/p>\n<p>un iniziatore\/innovatore osando realizzare formazioni sempre pi\u00f9 varie e talvolta atipiche.<\/p>\n<div class=\"gap\" style=\"line-height: 20px; height: 20px;\"><\/div>\n<h3>FORMAZIONE<\/h3>\n<p>Nel corso degli anni, e a fronte di una comprovata competenza riconosciuta da tutti, stiamo ora aprendo la maggior parte della formazione ad altri paesi in altre lingue con traduzioni simultanee: Dopo Spagna e Sud America; Si uniscono a noi Italia, Russia, Portogallo e paesi di lingua inglese, cos\u00ec come l&#8217;apertura di live training ai tempi di cittadini francesi provenienti da molti paesi: Hong Kong, Malesia, Montreal, Quebec, Polinesia, per n&#8217;citare solo un pochi..<\/p>\n<p><strong>Informazioni specifiche\/Consigli personali:<\/strong> <span \n                data-original-string='jvvKwcXOPuQXHHwjup3HEg==960vr8zkY\/Byay0eD3JMPVt2TeY4GfZXpKPisT6aaczCsk='\n                class='apbct-email-encoder'\n                title='This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.'>co<span class=\"apbct-blur\">*****<\/span>@<span class=\"apbct-blur\">******<\/span>rp.com<\/span> &#8211; Tel \/ Whatsapp \/ Signal \/ Telegram : +33640920700[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css_animation=&#8221;fadeInRight&#8221;]<\/p>\n<h3>I NOSTRI VALORI<\/h3>\n<p>Rispetto e valorizzazione della differenza nella semplicit\u00e0 e trasparenza. Il tuo benessere \u00e8 la nostra missione.<\/p>\n<p>\u00c8 anche un altro modo per trasformare, imparare, imparare, evolvere, cambiare attraverso i tanti strumenti di crescita personale oggi disponibili. Organizziamo eventi scolastici:<\/p>\n<ul>\n<li>Decodifica biologica di Christian Fl\u00e8che,<\/li>\n<li>Riflessologia totale della dott.ssa Martine Faure Alderson,<\/li>\n<li>Dalla numerologia e dai tarocchi di Richard Albacete.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner][vc_empty_space height=&#8221;70px&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;annulcenter&#8221;][vc_column_inner][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">I prossimi corsi di formazione<\/h2>\n<div class=\"gap\" style=\"line-height: 30px; height: 30px;\"><\/div>\n<div id=\"mec_skin_54802\" class=\"mec-wrap colorskin-custom  \">\r\n\r\n    \r\n    <div class=\"mec-tile\">\r\n        <div class=\"mec-calendar-topsec\">\r\n            <div class=\"mec-clear\">\r\n                                <div class=\"mec-skin-tile-month-navigator-container\">\r\n                    <div class=\"mec-month-navigator\" id=\"mec_month_navigator_54802_202607\"><div class=\"mec-calendar-header\"><h2>Luglio 2026<\/h2><\/div><div class=\"mec-next-month mec-load-month mec-next-month\" data-mec-year=\"2026\" data-mec-month=\"08\"><a href=\"#\" class=\"mec-load-month-link\">Agosto <i class=\"mec-sl-angle-right\"><\/i><\/a><\/div><\/div>\r\n                <\/div>\r\n                \r\n                <div class=\"mec-calendar-table\" id=\"mec_skin_events_54802\">\r\n                                            <div class=\"mec-month-container mec-month-container-selected\" id=\"mec_tile_month_54802_202607\" data-month-id=\"202607\"><div class=\"mec-wrap colorskin-custom\">\r\n    <div class=\"mec-event-tile-view\">\r\n            <\/div>\r\n    <\/div><\/div>\r\n                                    <\/div>\r\n\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    \r\n<\/div>\r\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_empty_space height=&#8221;90px&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;1&#8243; full_width_row=&#8221;true&#8221; padding_top=&#8221;80&#8243; padding_bottom=&#8221;70&#8243; bg_repeat=&#8221;repeat-y&#8221; el_class=&#8221;text-centered&#8221;][vc_column][vc_column_text]<\/p>\n<h2>ATTIVITA&#8217;<\/h2>\n<h4>IN VARIE DISCIPLINE<\/h4>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;45px&#8221;]<div class=\"dt-portfolio-shortcode slider-wrapper  owl-carousel dt-owl-carousel-init arrows-accent enable-mobile-arrows description-on-hover hover-style-two hover-scale content-align-centre\" data-padding-side=\"10\" data-autoslide=\"true\" data-delay=\"3000\" data-loop=\"false\" data-arrows=\"true\">\n\n<article class=\"post post-61167 dt_portfolio type-dt_portfolio status-publish has-post-thumbnail hentry dt_portfolio_category-formations-en-live-it dt_portfolio_category-formation-biodecodage-it dt_portfolio_category-485 dt_portfolio_category-484 text-centered\">\n\n\t<figure class=\"rollover-project rollover-active\">\n\t<a href=\"https:\/\/fpmdcorp.com\/it\/offre\/formazione-pratica-in-biodecodifica-ciclo-1-in-diretta-da-zoom-2023-2024\/\" class=\"layzr-bg\" title=\"Formazione in biodecodifica con la scuola di decodifica biologica di Christian Fle\u0300che live by zoom\"  aria-label=\"Post image\"><img fetchpriority=\"high\" decoding=\"async\" class=\"preload-me lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20396%20260&#39;%2F%3E\" data-src=\"https:\/\/fpmdcorp.com\/wp-content\/uploads\/2022\/05\/Formazione-in-biodecodifica-con-la-scuola-di-decodifica-biologica-di-Christian-Fle\u0300che-live-by-zoom-396x260.jpeg\" data-srcset=\"https:\/\/fpmdcorp.com\/wp-content\/uploads\/2022\/05\/Formazione-in-biodecodifica-con-la-scuola-di-decodifica-biologica-di-Christian-Fle\u0300che-live-by-zoom-396x260.jpeg 396w, https:\/\/fpmdcorp.com\/wp-content\/uploads\/2022\/05\/Formazione-in-biodecodifica-con-la-scuola-di-decodifica-biologica-di-Christian-Fle\u0300che-live-by-zoom.jpeg 399w\" loading=\"eager\" style=\"--ratio: 396 \/ 260\" sizes=\"(max-width: 396px) 100vw, 396px\" alt=\"Formazione-in-biodecodifica-con-la-scuola-di-decodifica-biologica-di-Christian-Fle\u0300che-live-by-zoom\" width=\"396\" height=\"260\"  \/><\/a>\t\t<figcaption class=\"rollover-content\">\n\t\t<div class=\"links-container\"><a href=\"https:\/\/fpmdcorp.com\/it\/offre\/formazione-pratica-in-biodecodifica-ciclo-1-in-diretta-da-zoom-2023-2024\/\" class=\"project-details\">Dettagli<\/a><\/div>\t\t\t\t<div class=\"rollover-content-container\">\n\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/fpmdcorp.com\/it\/offre\/formazione-pratica-in-biodecodifica-ciclo-1-in-diretta-da-zoom-2023-2024\/\" title=\"Formazione pratica in biodecodifica &#8211; Ciclo 1 in diretta da zoom 2023-2024\" rel=\"bookmark\">Formazione pratica in biodecodifica &#8211; Ciclo 1 in diretta da zoom 2023-2024<\/a><\/h3><div class=\"entry-meta portfolio-categories\"><span class=\"category-link\"><a href=\"https:\/\/fpmdcorp.com\/it\/project-category\/formations-en-live-it\/\" >Formazione a distanza<\/a>, <a href=\"https:\/\/fpmdcorp.com\/it\/project-category\/formation-biodecodage-it\/\" >Formazione biodecodifica<\/a><\/span><\/div>\t\t<\/div>\n\t\t\t\t\t<\/figcaption>\n\t<\/figure>\n<\/article>\n\n<\/div>[vc_empty_space height=&#8221;50px&#8221;][\/vc_column][\/vc_row][vc_row margin_top=&#8221;80&#8243; css=&#8221;.vc_custom_1465245036909{margin-bottom: -30px !important;}&#8221;][vc_column][vc_column_text]<\/p>\n<h4 style=\"text-align: center;\">NOTIZIA<\/h4>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;45px&#8221;][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][vc_column_text]<\/p>\n<h4 style=\"text-align: center;\">TESTIMONIANZE<\/h4>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;45px&#8221;]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav div {\n  width: 36px;\n  height: 36px;\n  border-radius: 500px;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav div:before,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav div:after {\n  border-width: 0px;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav div.owl-prev {\n  top: 50%;\n  transform: translateY(calc(-50% + 0px));\n  left: -43px;\n}\n@media all and (-ms-high-contrast: none) {\n  .testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav div.owl-prev {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav div.owl-prev i {\n  padding: 0px 0px 0px 0px;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav div.owl-next {\n  top: 50%;\n  transform: translateY(calc(-50% + 0px));\n  right: -43px;\n}\n@media all and (-ms-high-contrast: none) {\n  .testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav div.owl-next {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav div.owl-next i {\n  padding: 0px 0px 0px 0px;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav i {\n  font-size: 18px;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav div:not(:hover) i,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav div:not(:hover) i:before {\n  color: #ffffff;\n  background: none;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav div:hover i,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.owl-carousel .owl-nav div:hover i:before {\n  color: rgba(255,255,255,0.75);\n  background: none;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 .owl-dots {\n  top: calc(100% + 20px);\n  left: 50%;\n  transform: translateX(calc(-50% + 0px));\n}\n@media all and (-ms-high-contrast: none) {\n  .testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 .owl-dots {\n    transform: translateX(-50%);\n    margin-left: 0px;\n  }\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 .owl-dot {\n  width: 10px;\n  height: 10px;\n  margin: 0 8px;\n}\n@media screen and (max-width: 778px) {\n  .testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.hide-arrows.owl-carousel .owl-nav a {\n    display: none;\n  }\n}\n@media screen and (max-width: 778px) {\n  .testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.reposition-arrows.owl-carousel .owl-nav .owl-prev {\n    top: 50%;\n    transform: translateY(calc(-50% + 0px));\n    left: -18px;\n  }\n  .testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.reposition-arrows.owl-carousel .owl-nav .owl-next {\n    top: 50%;\n    transform: translateY(calc(-50% + 0px));\n    right: -18px;\n  }\n}\n@media screen and (max-width: 778px) and all and (-ms-high-contrast: none) {\n  .testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.reposition-arrows.owl-carousel .owl-nav .owl-prev {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n@media screen and (max-width: 778px) and all and (-ms-high-contrast: none) {\n  .testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.reposition-arrows.owl-carousel .owl-nav .owl-next {\n    transform: translateY(-50%);\n    margin-top: 0px;\n  }\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 .testimonial-item {\n  padding: 30px 30px 20px 30px;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 .testimonial-name,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 .testimonial-name a,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 .testimonial-name span {\n  margin-bottom: 0px;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 .testimonial-position {\n  margin-bottom: 20px;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 .testimonial-position,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 .testimonial-position span {\n  font-style: italic;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8  .testimonial-avatar {\n  padding: 0px 20px 20px 0px;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8  .testimonial-avatar a,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8  .testimonial-avatar span,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8  .testimonial-avatar img {\n  max-width: 80px;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 .dt-css-grid .testimonial-avatar img,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 .dt-css-grid .testimonial-avatar svg {\n  max-width: 100%;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.layout-5:not(.hide-testimonial-avatar) .content-wrap,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8.layout-6:not(.hide-testimonial-avatar) .content-wrap {\n  width: calc(100% - 80px - 20px - 0px);\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 .testimonial-content {\n  margin-bottom: 0px;\n  font-style: italic;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8  .testimonial-avatar,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8  .testimonial-avatar a.rollover,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8  .testimonial-avatar a.rollover *,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8  .testimonial-avatar img,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8  .testimonial-avatar .no-avatar,\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8  .testim-no-avatar {\n  border-radius: 500px;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8  .testimonial-avatar .no-avatar {\n  height: 80px;\n}\n.testimonials-carousel-shortcode.testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8  .testimonial-avatar .no-avatar {\n  font-size: 80px;\n  width: 80px;\n}<\/style><div class=\"owl-carousel testimonials-carousel-shortcode dt-testimonials-shortcode dt-owl-carousel-call testimonials-carousel-shortcode-id-fb07664cb7c1cd5045d80273cbec73a8 content-align-left layout-3 content-bg-on bullets-small-dot-stroke reposition-arrows arrows-bg-on dt-arrow-border-on dt-arrow-hover-border-on disable-arrows-hover-bg arrows-hover-bg-on  \" data-scroll-mode=\"page\" data-col-num=\"3\" data-wide-col-num=\"4\" data-laptop-col=\"3\" data-h-tablet-columns-num=\"2\" data-v-tablet-columns-num=\"1\" data-phone-columns-num=\"1\" data-auto-height=\"true\" data-col-gap=\"30\" data-stage-padding=\"0\" data-speed=\"1500\" data-autoplay=\"true\" data-autoplay_speed=\"6000\" data-arrows=\"true\" data-bullet=\"false\" data-next-icon=\"icon-ar-017-r\" data-prev-icon=\"icon-ar-017-l\"><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Nabou<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">proprietario della spa<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><p>Amma Assis: Il miglior programma che ho fatto quest&#8217;anno!!! L&#8217;allenamento di massaggio amma con Tony ha avuto un impatto su di me! \u00c8 un insegnante molto paziente e di talento. I miei clienti sono entusiasti quando ricevono la tecnica di Amma che mi ha insegnato!!<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Adeline<\/span><br \/><\/div><div class=\"testimonial-position\"><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Biodecodifica:<\/strong> Ciao David, torno da te dopo l&#8217;allenamento di questo fine settimana con Nelly. \u00c8 stato molto interessante e intenso. La scoperta della decodifica biologica mi ha incantato. Il gruppo \u00e8 stato gentile. Nelly \u00e8 una grande allenatrice: \u00e8 un&#8217;insegnante, ha catturato l&#8217;attenzione e si prende cura. Gli esercizi pratici sono stati istruttivi, soprattutto quando Nelly ci ha spiegato cosa stava succedendo in relazione alla teoria. Spero che anche il modulo 2 venga svolto faccia a faccia e con Nelly.<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">C\u00e9line<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">Saint Etienne - Assistante administrative<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Biodecodifica:<\/strong> &#8220;Formazione molto densa che mi ha permesso di cambiare la mia visione della malattia, di evolvermi verso un altro prisma di analisi e riflessione che mi &#8220;parla&#8221; molto meglio. Grazie!!!&#8221;<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Julie<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">Ma\u00e7onne en reconversion<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Biodecodifica<\/strong>: &#8220;Decodifica biologica&#8230; ci entriamo per curiosit\u00e0 e finiamo per voler fare tutto il corso! Da parte mia, mi piace particolarmente l&#8217;aspetto molto pratico, possiamo applicare quanto appreso dai primi moduli, e con risultati!!&#8221;<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">St\u00e9phanie<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">Assistante cabinet comptable<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><p>Biodecodifica: come tutti i moduli precedenti, i 3 giorni sono trascorsi rapidamente. Questo modulo 6 \u00e8 stato molto apprezzabile grazie all&#8217;ascolto, alla generosit\u00e0 e alla pazienza di Christian. Sapeva mettermi a mio agio e confidenza. 3d riguardava principalmente le revisioni ed \u00e8 stato davvero bello fare un riepilogo dei moduli passati. Lo scambio era all&#8217;appuntamento ed \u00e8 stato molto piacevole. Grazie Cristiano<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">C\u00e9cile<\/span><br \/><\/div><div class=\"testimonial-position\"><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Amma Assis:<\/strong> Sono stata addestrata da Tony! Questo corso \u00e8 il migliore che abbia mai fatto!! L&#8217;aspetto tecnico \u00e8 essenziale e la ripetizione \u00e8 essenziale. Abbiamo ricevuto un CD alla fine del corso, ci ha permesso di esercitarci e migliorare. L&#8217;aspetto marketing \u00e8 chiarissimo con Tony. Grazie a lui, mi \u00e8 piaciuto portare il massaggio ovunque. Approvo al 100%. Seri e solidi&#8230; Radici e ali per iniziare&#8230;<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Madeleine<\/span><br \/><\/div><div class=\"testimonial-position\"><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Biodecodifica:<\/strong> formazione densa ed emozionante. Grazie ancora a Nelly per il suo dinamismo, gentilezza e supporto. Consiglio vivamente questa formazione. Non vedo l&#8217;ora di continuare a scoprire i prossimi moduli!<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Marie<\/span><br \/><\/div><div class=\"testimonial-position\"><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Bio PNL:<\/strong> formazione molto buona. Non vedo l&#8217;ora di fare PNL 2 con Annie. Preferibilmente faccia a faccia se \u00e8 in zoom ovviamente far\u00f2 l&#8217;allenamento con piacere.<\/p>\n<div dir=\"auto\"><\/div>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Pascale<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">Ergotherapeute, kinesiologue<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><div dir=\"auto\"><strong>Biodecoding<\/strong>: Dopo aver seguito i primi 4 moduli con Nelly, vorrei testimoniare la qualit\u00e0 della tua formazione e del trainer. Il programma, la pedagogia con i diversi ritmi (richiamo di quanto detto, teorie, protocolli) sono efficaci e buoni Nelly ci accompagna con gentilezza e in questo corso e ci ascolta. Consiglio vivamente questa formazione che continuo.<\/div>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Laurence<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">Praticienne TCSB et art-th\u00e9rapie<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Biodecoding:<\/strong> Un vero piacere che questo modulo&#8230;di condivisione, generosit\u00e0 e semplicit\u00e0. Grazie a Nelly e a tutte le donne presenti!<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Mina<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">Linea di business - grado farmaceutico<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Biodecodifica:<\/strong> voglio ringraziare Jonathan per la sua pazienza con il nostro gruppo. L&#8217;argomento era denso e dovevamo affrontarlo lentamente e Jonathan padroneggiava perfettamente il nostro ritmo. Le sue spiegazioni sono state molto chiare, ben illustrate ed \u00e8 rimasto attento con i 18 colleghi fino alla fine della formazione. Inoltre ha prolungato la domenica per garantire che alcuni argomenti dei moduli precedenti fossero trattati, su richiesta di alcuni di noi. Ho apprezzato molto la sua visione di un futuro ideale in cui le persone avrebbero uno spazio sicuro per esprimere le proprie emozioni senza giudizi e che avrebbe consentito loro una migliore qualit\u00e0 della vita con le proprie risorse. Grazie per averci fornito questo supporto.<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Sandra<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">Infermiera e terapista bioenergetica<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><div dir=\"auto\"><strong>Biodecodifica<\/strong>: Jonathan \u00e8 molto attento e desideroso di rispondere ai bisogni e alle domande di tutti. Con la voglia di fare il meglio nel rispetto dei propri obiettivi. Grazie a lui per questo weekend di allenamento.<\/div>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Dani\u00e8le<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">dentista in pensione<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><p>Biodecodifica: il corso con Jonathan \u00e8 emozionante e favoloso.<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Pierre<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">geobiologo e magnetizzatore<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Biodecodifica:<\/strong> Ciao, ancora una volta un allenamento molto gratificante, i formatori sono attenti e attenti ai nostri pi\u00f9 piccoli dubbi.<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Charlotte<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">autoimprenditore turismo-traduzione-benessere.<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Biodecodifica:<\/strong> mi \u00e8 piaciuto molto il training e il nostro trainer. Per quanto riguarda il modulo 1, ho l&#8217;impressione che stia andando troppo veloce e che non ci sia abbastanza tempo per approfondire (perfezionista) e ho trovato Nelly molto competente. In ogni caso sono motivato a continuare e soddisfatto. Grazie Nelly<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Ma\u00ebva<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">La R\u00e9union - Guida al benessere - Praticante in psicologia positiva<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Biodecodifica<\/strong>: Felice di questa formazione, una formazione arricchente e che consente un&#8217;evoluzione verso un accompagnamento profondo. Il trainer \u00e8 eccezionale e ci aiuta a raggiungere obiettivi inaspettati in cos\u00ec poco tempo.<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Christine<\/span><br \/><\/div><div class=\"testimonial-position\"><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>BIO PNL<\/strong>: un grazie di cuore ad Annie per questo super zoom, tanto pi\u00f9 conveniente; continuate cos\u00ec&#8230;<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Amel<\/span><br \/><\/div><div class=\"testimonial-position\"><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>BIO PNL:<\/strong> Grazie a tutti coloro che hanno contribuito a questi 4 giorni di formazione. Mi hanno permesso ancora una volta di aprirmi a te, a questa nuova conoscenza, tutti questi scambi mi confortano e mi guidano nelle mie scelte&#8230; quindi un enorme grazie e in attesa di ulteriori scambi<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Marie<\/span><br \/><\/div><div class=\"testimonial-position\"><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>BIO PNL:<\/strong> Non ho parole per esprimere quello che provo, sono stati 4 giorni cos\u00ec intensi.<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Christine<\/span><br \/><\/div><div class=\"testimonial-position\"><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>BIO PNL:<\/strong> Questo 1\u00b0 corso di PNL in zoom \u00e8 stato fantastico e le dinamiche di gruppo sono state molto presenti, non vedo l&#8217;ora di fare il resto in zoom (vedi adattamento al Covid) e beneficio secondario in zoom risparmio sui costi di trasporto, hotel, pasti per fallo pi\u00f9 velocemente Grazie ad Annie che \u00e8 stata cos\u00ec gentile da adattarsi alle circostanze &#8220;covid&#8221; per permetterci di vivere questi 4 giorni molto gratificanti ed essenziali per il futuro. Grazie a tutti per le vostre condivisioni e scambi ea presto spero per il resto.<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Nathalie<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">Arteterapeuta, Numerologa e Formatore di Enneagramma.<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><p>Biodecodifica: Un corso molto bello, ricco e potente di strumenti di apprendimento, che permettono di comprendere in profondit\u00e0 i legami tra corpo, mente ed emozioni, e di mettere in pratica il rilascio dei blocchi pi\u00f9 profondi. Una pedagogia benevola e un formatore coinvolto, grazie.<\/p>\n<div dir=\"auto\"><\/div>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Daniele<\/span><br \/><\/div><div class=\"testimonial-position\"><span class=\"text-secondary color-secondary\">In pensione, dottore in chirurgia dentale<\/span><\/div><\/div><\/div><div class=\"testimonial-content\"><div class=\"gmail_attr\" dir=\"ltr\"><strong>Biodecodifica:<\/strong> Ciao David, ho appena seguito il corso di Nelly e la ringrazio per tutto ci\u00f2 che ci ha insegnato e portato a questa lezione di vita. Era appassionato. grazie<\/div>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Sandra<\/span><br \/><\/div><div class=\"testimonial-position\"><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Biodecodifica:<\/strong> Buonasera David, una formazione ricca ed entusiasmante. Un modulo denso perch\u00e9 ci confrontiamo con le nostre stesse serrature. Nelly ha una grande pedagogia ed empatia. Possa essere comodo anche per lei. Ti amo. Un grande grazie<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Louisette<\/span><br \/><\/div><div class=\"testimonial-position\"><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Biodecodifica:<\/strong> questa formazione \u00e8 stata ancora una volta completamente adattata alle mie aspettative in termini di ritmo, contenuto e forma. Grazie ancora a Nelly per la sua pedagogia e la sua empatia e anche al gruppo.<\/p>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Prescillia<\/span><br \/><\/div><div class=\"testimonial-position\"><\/div><\/div><\/div><div class=\"testimonial-content\"><p><strong>Biodecodifica:<\/strong> Ciao, sono rimasta soddisfatta della formazione fornita da Nelly, mi \u00e8 piaciuto il suo modo di insegnare e di darci le chiavi per praticare i protocolli.<\/p>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">,<\/div>\n<\/div><\/div><div class=\"testimonial-item\"><div class=\"testimonial-author\"><div class=\"testimonial-avatar\"><span class=\"testim-no-avatar\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"80\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 60 60\" style=\"enable-background:new 0 0 60 60;\" xml:space=\"preserve\">\n<path d=\"M30,1.5c-16.542,0-30,12.112-30,27c0,5.204,1.646,10.245,4.768,14.604c-0.591,6.537-2.175,11.39-4.475,13.689\n\tc-0.304,0.304-0.38,0.769-0.188,1.153C0.275,58.289,0.625,58.5,1,58.5c0.046,0,0.092-0.003,0.139-0.01\n\tc0.405-0.057,9.813-1.411,16.618-5.339C21.621,54.71,25.737,55.5,30,55.5c16.542,0,30-12.112,30-27S46.542,1.5,30,1.5z M16,32.5\n\tc-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S18.206,32.5,16,32.5z M30,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4\n\tS32.206,32.5,30,32.5z M44,32.5c-2.206,0-4-1.794-4-4s1.794-4,4-4s4,1.794,4,4S46.206,32.5,44,32.5z\"\/>\n<\/svg><\/span><\/div><div class=\"testimonial-vcard\"><div class=\"testimonial-name\"><span class=\"text-primary\">Christine<\/span><br \/><\/div><div class=\"testimonial-position\"><\/div><\/div><\/div><div class=\"testimonial-content\"><div dir=\"ltr\"><strong>Biodecodifica:<\/strong> soddisfatto dell&#8217;allenamento con Nelly. Il contenuto \u00e8 esplicito, il ritmo \u00e8 ben ritmato. Non ho visto passare questi 3 giorni. Nelly sa benissimo come essere un pugno di ferro in un guanto di velluto.<\/div>\n<\/div><\/div><\/div>[vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;vc_default&#8221; full_width=&#8221;stretch_row_content_no_spaces&#8221; full_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; css_animation=&#8221;bounceInRight&#8221; full_width_row=&#8221;true&#8221; css=&#8221;.vc_custom_1687792410939{margin-top: -50px !important;background-image: url(https:\/\/fpmdcorp.com\/wp-content\/uploads\/2023\/06\/fpmd-intro-hp.jpg?id=65543) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243; css=&#8221;.vc_custom_1660668917228{padding-top: 50px !important;padding-right: 50px !important;padding-bottom: 50px !important;padding-left: 50px !important;background-color: rgba(2,2,2,0.09) !important;*background-color: rgb(2,2,2) !important;border-radius: 15px !important;}&#8221;][vc_column_text] FPMD CORP PROMOZIONI, ORGANIZZAZIONI ED EVENTI [\/vc_column_text][vc_empty_space][vc_column_text] Benvenuti nel sito ufficiale di FPMD Corp, siamo una societ\u00e0 Internet internazionale: il&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_analytify_skip_tracking":false,"footnotes":""},"class_list":["post-59104","page","type-page","status-publish","hentry","description-off"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/fpmdcorp.com\/it\/wp-json\/wp\/v2\/pages\/59104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fpmdcorp.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fpmdcorp.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fpmdcorp.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fpmdcorp.com\/it\/wp-json\/wp\/v2\/comments?post=59104"}],"version-history":[{"count":5,"href":"https:\/\/fpmdcorp.com\/it\/wp-json\/wp\/v2\/pages\/59104\/revisions"}],"predecessor-version":[{"id":65552,"href":"https:\/\/fpmdcorp.com\/it\/wp-json\/wp\/v2\/pages\/59104\/revisions\/65552"}],"wp:attachment":[{"href":"https:\/\/fpmdcorp.com\/it\/wp-json\/wp\/v2\/media?parent=59104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}